{"id":5070,"date":"2026-05-08T16:29:02","date_gmt":"2026-05-08T14:29:02","guid":{"rendered":"https:\/\/burgersequipment.nl\/machines\/manitou-mh25-4-buggy\/"},"modified":"2026-05-08T16:29:02","modified_gmt":"2026-05-08T14:29:02","slug":"manitou-mh25-4-buggy","status":"publish","type":"be_machine","link":"https:\/\/burgersequipment.nl\/de\/machines\/manitou-mh25-4-buggy\/","title":{"rendered":"Manitou MH25-4 Buggy"},"content":{"rendered":"<p>Manitou MH25-4<\/p>\n<p>  Baujahr: 2018<br \/>  Stunden: 2001 Stunden<br \/>  Motor: Kubota<br \/>  Gewicht: 4340 kg<br \/>  Hebeh\u00f6he: 3,3 m<br \/>  Lichte H\u00f6he: 1,835 m<br \/>  Mast: Sperrholz<br \/>  Hebekapazit\u00e4t: 2500 kg<br \/>  Antrieb : 4&#215;4<br \/>  Beilage: Seitenschieber<br \/>  CE-Maschine<br \/>  Preis ohne Mehrwertsteuer<\/p>\n<p>  Maschine aus unserer Mietflotte (wird noch vermietet)<br \/>  Weitere Fotos und Videos finden Sie auf unserer Website<br \/>  Die Maschine ist in gutem Zustand<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Manitou MH25-4 Baujahr: 2018 Betriebsstunden: 2001 Stunden Motor: Kubota Gewicht: 4340 kg Hubh\u00f6he: 3.3 mtr Lichte H\u00f6he: 1.835 mtr Mast: Triplex Tragf\u00e4higkeit: 2500 kg Antrieb: 4&#215;4 Anbauger\u00e4t: Seitenschieber CE-Maschine Preis ohne MwSt. Maschine aus&#8230;<\/p>\n","protected":false},"featured_media":5077,"template":"","meta":{"behs_hexon_id":"688326db-4de9-488d-8723-2ad659f677ae","behs_stock_number":"46539","behs_external_stock_number":"BE1862","behs_license_plate":"TXG41J","behs_product_group":"heftrucks","behs_product_group_display":"Gabelstapler","behs_brand":"Manitou","behs_model":"MH25-4 Buggy","behs_type":"MH25-4 Buggy","behs_body_type":"Ruw-terreinheftruck","behs_year":"2018","behs_first_registration":"","behs_usage_value":"2001","behs_usage_unit":"uren","behs_hour_meter":"2001","behs_odometer":"","behs_price":"31500","behs_price_trade":"","behs_price_public":"31500","behs_export_price":"","behs_currency":"EUR","behs_vat_margin":"B","behs_fuel":"Diesel","behs_transmission":"","behs_machine_weight":"4340","behs_location":"","behs_country":"","behs_serial_number":"","behs_working_height":"","behs_platform_height":"","behs_horizontal_reach":"","behs_lift_capacity":"2500","behs_platform_capacity":"","behs_forklift_lift_height":"330","behs_forklift_free_lift":"","behs_mast_type":"","behs_load_capacity":"","behs_wheelbase":"","behs_emission_class":"","behs_color":"overig","behs_status":"","behs_language_source":"nl","behs_last_synced_at":"2026-05-08 16:29:03","behs_price_display":"\u20ac 31.500,00","behs_usage_display":"2.001 uur","behs_machine_weight_display":"4.340 kg","behs_drive_type":"motorisch","behs_image_count":"20","behs_gallery_ids":"4186,4187,4188,4189,4190,4191,4192,4193,4194,4195,4196,4197,4198,4199,4200,4201,4202,4203,4204","behs_gallery_urls":"https:\/\/burgersequipment.nl\/wp-content\/uploads\/2026\/05\/45424998-2.jpg,https:\/\/burgersequipment.nl\/wp-content\/uploads\/2026\/05\/45424998-3.jpg,https:\/\/burgersequipment.nl\/wp-content\/uploads\/2026\/05\/45424998-4.jpg,https:\/\/burgersequipment.nl\/wp-content\/uploads\/2026\/05\/45424998-5.jpg,https:\/\/burgersequipment.nl\/wp-content\/uploads\/2026\/05\/45424998-6.jpg,https:\/\/burgersequipment.nl\/wp-content\/uploads\/2026\/05\/45424998-7.jpg,https:\/\/burgersequipment.nl\/wp-content\/uploads\/2026\/05\/45424998-8.jpg,https:\/\/burgersequipment.nl\/wp-content\/uploads\/2026\/05\/45424998-9.jpg,https:\/\/burgersequipment.nl\/wp-content\/uploads\/2026\/05\/45424998-10.jpg,https:\/\/burgersequipment.nl\/wp-content\/uploads\/2026\/05\/45424998-11.jpg,https:\/\/burgersequipment.nl\/wp-content\/uploads\/2026\/05\/45424998-12.jpg,https:\/\/burgersequipment.nl\/wp-content\/uploads\/2026\/05\/45424998-13.jpg,https:\/\/burgersequipment.nl\/wp-content\/uploads\/2026\/05\/45424998-14.jpg,https:\/\/burgersequipment.nl\/wp-content\/uploads\/2026\/05\/45424998-15.jpg,https:\/\/burgersequipment.nl\/wp-content\/uploads\/2026\/05\/45424998-16.jpg,https:\/\/burgersequipment.nl\/wp-content\/uploads\/2026\/05\/45424998-17.jpg,https:\/\/burgersequipment.nl\/wp-content\/uploads\/2026\/05\/45424998-18.jpg,https:\/\/burgersequipment.nl\/wp-content\/uploads\/2026\/05\/45424998-19.jpg,https:\/\/burgersequipment.nl\/wp-content\/uploads\/2026\/05\/45424998-20.jpg","behs_featured_image_id":"4185","behs_featured_image_url":"https:\/\/burgersequipment.nl\/wp-content\/uploads\/2026\/05\/45424998-1.jpg","behs_fork_length":"","behs_odometer_unit":"","behs_price_action":"","behs_reference":"46539","behs_description":"Manitou MH25-4<br> <br>  Baujahr: 2018<br>  Stunden: 2001 Stunden<br>  Motor: Kubota<br>  Gewicht: 4340 kg<br>  Hebeh\u00f6he: 3,3 m<br>  Lichte H\u00f6he: 1,835 m<br>  Mast: Sperrholz<br>  Hebekapazit\u00e4t: 2500 kg<br>  Antrieb : 4x4<br>  Beilage: Seitenschieber<br>  CE-Maschine<br>  Preis ohne Mehrwertsteuer<br> <br>  Maschine aus unserer Mietflotte (wird noch vermietet)<br>  Weitere Fotos und Videos finden Sie auf unserer Website<br>  Die Maschine ist in gutem Zustand","behs_title":"Manitou MH25-4 Buggy","behs_is_active":"1"},"be_product_group":[19],"be_machine_brand":[16],"be_fuel_type":[42],"class_list":["post-5070","be_machine","type-be_machine","status-publish","has-post-thumbnail","hentry","be_product_group-heftrucks","be_machine_brand-manitou","be_fuel_type-diesel"],"_links":{"self":[{"href":"https:\/\/burgersequipment.nl\/de\/wp-json\/wp\/v2\/be_machine\/5070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/burgersequipment.nl\/de\/wp-json\/wp\/v2\/be_machine"}],"about":[{"href":"https:\/\/burgersequipment.nl\/de\/wp-json\/wp\/v2\/types\/be_machine"}],"version-history":[{"count":0,"href":"https:\/\/burgersequipment.nl\/de\/wp-json\/wp\/v2\/be_machine\/5070\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/burgersequipment.nl\/de\/wp-json\/wp\/v2\/media\/5077"}],"wp:attachment":[{"href":"https:\/\/burgersequipment.nl\/de\/wp-json\/wp\/v2\/media?parent=5070"}],"wp:term":[{"taxonomy":"be_product_group","embeddable":true,"href":"https:\/\/burgersequipment.nl\/de\/wp-json\/wp\/v2\/be_product_group?post=5070"},{"taxonomy":"be_machine_brand","embeddable":true,"href":"https:\/\/burgersequipment.nl\/de\/wp-json\/wp\/v2\/be_machine_brand?post=5070"},{"taxonomy":"be_fuel_type","embeddable":true,"href":"https:\/\/burgersequipment.nl\/de\/wp-json\/wp\/v2\/be_fuel_type?post=5070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}